{"id":2383500,"date":"2025-12-24T16:55:35","date_gmt":"2025-12-24T19:55:35","guid":{"rendered":"https:\/\/ecompare.com.br\/lojas\/2025\/12\/vestido-midi-feminino-com-recorte-franzido-preto\/"},"modified":"2026-01-02T19:35:14","modified_gmt":"2026-01-02T22:35:14","slug":"vestido-midi-feminino-com-recorte-franzido-preto","status":"publish","type":"post","link":"https:\/\/ecompare.com.br\/lojas\/2025\/12\/vestido-midi-feminino-com-recorte-franzido-preto\/","title":{"rendered":"vestido midi feminino com recorte franzido preto"},"content":{"rendered":"<h2>Moda Feminina > Roupas > Vestidos<\/h2>\n<h3>O pre\u00e7o de vestido midi feminino com recorte franzido preto no dia acima especificado era de <strong>R$ 129.99<\/strong>.<\/h3>\n<p>Confira o pre\u00e7o atual aqui: <a href=\"https:\/\/www.awin1.com\/pclick.php?p=42283175133&#038;a=690303&#038;m=17648\" target=\"_blank\" rel=\"noopener sponsored\"><img decoding=\"async\" src=\"https:\/\/ui.awin.com\/images\/upload\/merchant\/profile\/17648.png\" alt=\"vestido midi feminino com recorte franzido preto\" \/> &#8211; nas lojas C&#038;A _<\/a><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/cea.vteximg.com.br\/arquivos\/ids\/59270908\/Foto-0.jpg?v=638923487876400000\" alt=\"vestido midi feminino com recorte franzido preto\" \/><\/p>\n<h4>Aproveite e pesquise o pre\u00e7o deste produto em dezenas de lojas dos marketplaces abaixo:<\/h4>\n<p><a href=\"https:\/\/www.magazinevoce.com.br\/magazineezu\/busca\/vestido midi feminino com recorte franzido preto\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png\" alt=\"Pesquise no Magazine eZu\" \/> &#8211; da Parceria MAGALU<\/a>.<\/p>\n<hr \/>\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-5987304558705355\" crossorigin=\"anonymous\"><\/script><br \/>\n<ins class=\"adsbygoogle\" style=\"display: block;\" data-ad-format=\"autorelaxed\" data-ad-client=\"ca-pub-5987304558705355\" data-ad-slot=\"6675008826\"><\/ins><br \/>\n<script>\n     (adsbygoogle = window.adsbygoogle || ).push();\n<\/script><\/p>\n<hr \/>\n<p>Ainda n\u00e3o encontrou a melhor op\u00e7\u00e3o de compra? Oferecemos outra possibilidade de <strong>busca<\/strong>, mais ampla, para <a href=\"https:\/\/ecompare.com.br\/lojas\/resultados-da-pesquisa\/?q=vestido midi feminino com recorte franzido preto#gsc.tab=0&amp;gsc.q=vestido midi feminino com recorte franzido preto&amp;gsc.page=1\" target=\"_top\" rel=\"noopener\">vestido midi feminino com recorte franzido preto, clique e continue <strong>pesquisando&#8230;<\/strong><\/a><\/p>\n<hr \/>\n<p>C\u00f3digo: 42283175133648995717648R$ 58627<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R$ 129.99 nas lojas <a href=\"https:\/\/www.cea.com.br\/vestido-midi-feminino-com-recorte-franzido-preto-1100941-preto\/p?utm_source=zanox&#038;utm_medium=afiliados&#038;idsku=6489957&#038;utm_content=Moda_Feminina__Roupas__Vestidos&#038;utm_campaign=6489957&#038;utm_source=awin&#038;utm_medium=affiliate&#038;utm_id=&#038;utm_term=690303\" target=\"_blank\" rel=\"sponsored\">C&#038;A BR<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[5],"tags":[8],"class_list":["post-2383500","post","type-post","status-publish","format-standard","hentry","category-produtos","tag-ca-br"],"_links":{"self":[{"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/posts\/2383500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/comments?post=2383500"}],"version-history":[{"count":0,"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/posts\/2383500\/revisions"}],"wp:attachment":[{"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/media?parent=2383500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/categories?post=2383500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/tags?post=2383500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}