{"id":2029742,"date":"2025-10-07T23:23:05","date_gmt":"2025-10-08T02:23:05","guid":{"rendered":"https:\/\/ecompare.com.br\/lojas\/2025\/10\/atorvastatina-calcica-20mg-ems-30-comprimidos-revestidos-39028743369\/"},"modified":"2025-10-07T23:23:05","modified_gmt":"2025-10-08T02:23:05","slug":"atorvastatina-calcica-20mg-ems-30-comprimidos-revestidos-39028743369","status":"publish","type":"post","link":"https:\/\/ecompare.com.br\/lojas\/2025\/10\/atorvastatina-calcica-20mg-ems-30-comprimidos-revestidos-39028743369\/","title":{"rendered":"Atorvastatina C\u00e1lcica 20mg EMS 30 Comprimidos Revestidos &#8211; 39028743369"},"content":{"rendered":"<h2><\/h2>\n<h3>O pre\u00e7o de Atorvastatina C\u00e1lcica 20mg EMS 30 Comprimidos Revestidos no dia acima especificado era de <strong>R$ 16.99<\/strong>.<\/h3>\n<p>Confira o pre\u00e7o atual aqui: <a href=\"https:\/\/www.awin1.com\/pclick.php?p=39028743369&#038;a=690303&#038;m=68224\" target=\"_blank\" rel=\"noopener sponsored\"><img decoding=\"async\" src=\"https:\/\/ui.awin.com\/images\/upload\/merchant\/profile\/68224.png\" alt=\"Atorvastatina C\u00e1lcica 20mg EMS 30 Comprimidos Revestidos\" \/> &#8211; nas lojas  Drogal _<\/a><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/drogal.vteximg.com.br\/arquivos\/ids\/186468_2\" alt=\"Atorvastatina C\u00e1lcica 20mg EMS 30 Comprimidos Revestidos\" \/><br \/>\nO que \u00e9 Atorvastatina C\u00e1lcica 20mg EMS e para que serve? Atorvastatina&nbsp;\u00e9 um medicamento indicado para tratar hipercolesterolemia e hipercolesterolemia, que s\u00e3o basicamente o aumento de HDL (tipo de colesterol) e outro tipos de gordura no sangue. A atorvastatina c\u00e1lcica \u00e9 indicada para preven\u00e7\u00e3o secund\u00e1ria&nbsp; de s\u00edndrome coron\u00e1ria aguda e complica\u00e7\u00f5es cardiovasculares como infarto do mioc\u00e1rdio AVC, insufici\u00eancia card\u00edaca congestiva e de angina.    Como a Atorvastatina C\u00e1lcica 20mg EMS funciona?A a\u00e7\u00e3o da atorvastatina c\u00e1lcica se d\u00e1 pela inibi\u00e7\u00e3o de produ\u00e7\u00e3o de colesterol pelo f\u00edgado, e aumento da absor\u00e7\u00e3o e destrui\u00e7\u00e3o de fra\u00e7\u00f5es prejudiciais (LDL) do colesterol.    Como tomar a Atorvastatina C\u00e1lcica 20mg EMS?Atorvastatina c\u00e1lcica deve ser prescrita por um m\u00e9dico, a dose do medicamento pode variar de 10 a 80mg de acordo com os n\u00edveis sangu\u00edneos de colesterol sangu\u00edneo no paciente. Posologia: Tomar 1 comprimido ao dia a qualquer hora do dia. Ap\u00f3s o inicio do tratamento, os efeitos podem levar de 2 a 4 semanas, podendo ser necess\u00e1ria uma reavalia\u00e7\u00e3o.    Quais s\u00e3o as rea\u00e7\u00f5es adversas de Atorvastatina C\u00e1lcica 20mg EMS?  A atorvastatina c\u00e1lcica \u00e9 geralmente bem tolerada. As rea\u00e7\u00f5es adversas foram geralmente de natureza leve e transit\u00f3ria. Os efeitos adversos mais frequentes comum, ocorrem em 1% ou mais dos pacientes que utilizam este medicamento que podem ser associados ao tratamento com atorvastatina c\u00e1lcica s\u00e3o: Nasofaringite, hiperglicemia, dor de garganta, sangramento nasal, diarreia, m\u00e1 digest\u00e3o, n\u00e1usea, flatul\u00eancia, dor nas articula\u00e7\u00f5es, dor nas extremidades, dor nos m\u00fasculos e ossos, espasmos musculares, incha\u00e7o da articula\u00e7\u00e3o, altera\u00e7\u00f5es nas fun\u00e7\u00f5es do f\u00edgado, aumento da creatina fosfoquinase sangu\u00ednea.<\/p>\n<h4>Aproveite e pesquise o pre\u00e7o deste produto em dezenas de lojas dos marketplaces abaixo:<\/h4>\n<p><a href=\"https:\/\/www.magazinevoce.com.br\/magazineezu\/busca\/Atorvastatina C\u00e1lcica 20mg EMS 30 Comprimidos Revestidos\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png\" alt=\"Pesquise no Magazine eZu\" \/> &#8211; da Parceria MAGALU<\/a>.<\/p>\n<hr \/>\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-5987304558705355\" crossorigin=\"anonymous\"><\/script><br \/>\n<ins class=\"adsbygoogle\" style=\"display: block;\" data-ad-format=\"autorelaxed\" data-ad-client=\"ca-pub-5987304558705355\" data-ad-slot=\"6675008826\"><\/ins><br \/>\n<script>\n     (adsbygoogle = window.adsbygoogle || ).push();\n<\/script><\/p>\n<hr \/>\n<p>Ainda n\u00e3o encontrou a melhor op\u00e7\u00e3o de compra? Oferecemos outra possibilidade de <strong>busca<\/strong>, mais ampla, para <a href=\"https:\/\/ecompare.com.br\/lojas\/resultados-da-pesquisa\/?q=Atorvastatina C\u00e1lcica 20mg EMS 30 Comprimidos Revestidos#gsc.tab=0&amp;gsc.q=Atorvastatina C\u00e1lcica 20mg EMS 30 Comprimidos Revestidos&amp;gsc.page=1\" target=\"_top\" rel=\"noopener\">Atorvastatina C\u00e1lcica 20mg EMS 30 Comprimidos Revestidos, clique e continue <strong>pesquisando&#8230;<\/strong><\/a><\/p>\n<hr \/>\n<p>C\u00f3digo: 390287433698889R$ 16.9916.9968224R$ 97314<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R$ 16.99 nas lojas <a href=\"https:\/\/www.drogal.com.br\/atorvastatina-calcica-20mg-30-comprimidos-revestidos-ems\/p?idsku=8889&#038;utm_source=awin&#038;utm_medium=affiliate&#038;utm_id=&#038;utm_term=690303\" target=\"_blank\" rel=\"sponsored\">Drogal BR<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[5],"tags":[113411],"class_list":["post-2029742","post","type-post","status-publish","format-standard","hentry","category-produtos","tag-drogal-br"],"_links":{"self":[{"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/posts\/2029742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/comments?post=2029742"}],"version-history":[{"count":0,"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/posts\/2029742\/revisions"}],"wp:attachment":[{"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/media?parent=2029742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/categories?post=2029742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/tags?post=2029742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}