{"id":2029471,"date":"2025-10-11T00:23:43","date_gmt":"2025-10-11T03:23:43","guid":{"rendered":"https:\/\/ecompare.com.br\/lojas\/2025\/10\/cordarex-25mg-30-comprimidos-39028743069\/"},"modified":"2025-10-11T00:23:43","modified_gmt":"2025-10-11T03:23:43","slug":"cordarex-25mg-30-comprimidos-39028743069","status":"publish","type":"post","link":"https:\/\/ecompare.com.br\/lojas\/2025\/10\/cordarex-25mg-30-comprimidos-39028743069\/","title":{"rendered":"Cordarex 2,5mg 30 Comprimidos &#8211; 39028743069"},"content":{"rendered":"<h2><\/h2>\n<h3>O pre\u00e7o de Cordarex 2,5mg 30 Comprimidos no dia acima especificado era de <strong>R$ 37.99<\/strong>.<\/h3>\n<p>Confira o pre\u00e7o atual aqui: <a href=\"https:\/\/www.awin1.com\/pclick.php?p=39028743069&#038;a=690303&#038;m=68224\" target=\"_blank\" rel=\"noopener sponsored\"><img decoding=\"async\" src=\"https:\/\/ui.awin.com\/images\/upload\/merchant\/profile\/68224.png\" alt=\"Cordarex 2,5mg 30 Comprimidos\" \/> &#8211; nas lojas  Drogal _<\/a><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/drogal.vteximg.com.br\/arquivos\/ids\/263105_2\" alt=\"Cordarex 2,5mg 30 Comprimidos\" \/><\/p>\n<h4>Aproveite e pesquise o pre\u00e7o deste produto em dezenas de lojas dos marketplaces abaixo:<\/h4>\n<p><a href=\"https:\/\/www.magazinevoce.com.br\/magazineezu\/busca\/Cordarex 2,5mg 30 Comprimidos\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png\" alt=\"Pesquise no Magazine eZu\" \/> &#8211; da Parceria MAGALU<\/a>.<\/p>\n<hr \/>\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-5987304558705355\" crossorigin=\"anonymous\"><\/script><br \/>\n<ins class=\"adsbygoogle\" style=\"display: block;\" data-ad-format=\"autorelaxed\" data-ad-client=\"ca-pub-5987304558705355\" data-ad-slot=\"6675008826\"><\/ins><br \/>\n<script>\n     (adsbygoogle = window.adsbygoogle || ).push();\n<\/script><\/p>\n<hr \/>\n<p>Ainda n\u00e3o encontrou a melhor op\u00e7\u00e3o de compra? Oferecemos outra possibilidade de <strong>busca<\/strong>, mais ampla, para <a href=\"https:\/\/ecompare.com.br\/lojas\/resultados-da-pesquisa\/?q=Cordarex 2,5mg 30 Comprimidos#gsc.tab=0&amp;gsc.q=Cordarex 2,5mg 30 Comprimidos&amp;gsc.page=1\" target=\"_top\" rel=\"noopener\">Cordarex 2,5mg 30 Comprimidos, clique e continue <strong>pesquisando&#8230;<\/strong><\/a><\/p>\n<hr \/>\n<p>C\u00f3digo: 390287430698491R$ 37.9937.9968224R$ 97314<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R$ 37.99 nas lojas <a href=\"https:\/\/www.drogal.com.br\/cordarex-25mg-30-comprimidos\/p?idsku=8491&#038;utm_source=awin&#038;utm_medium=affiliate&#038;utm_id=&#038;utm_term=690303\" target=\"_blank\" rel=\"sponsored\">Drogal BR<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[5],"tags":[113411],"class_list":["post-2029471","post","type-post","status-publish","format-standard","hentry","category-produtos","tag-drogal-br"],"_links":{"self":[{"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/posts\/2029471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/comments?post=2029471"}],"version-history":[{"count":0,"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/posts\/2029471\/revisions"}],"wp:attachment":[{"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/media?parent=2029471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/categories?post=2029471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/tags?post=2029471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}