{"id":2010008,"date":"2025-10-11T10:31:01","date_gmt":"2025-10-11T13:31:01","guid":{"rendered":"https:\/\/ecompare.com.br\/lojas\/2025\/10\/allexofedrin-120mg-10-comprimidos-revestidos-39028732806\/"},"modified":"2025-10-22T16:02:29","modified_gmt":"2025-10-22T19:02:29","slug":"allexofedrin-120mg-10-comprimidos-revestidos-39028732806","status":"publish","type":"post","link":"https:\/\/ecompare.com.br\/lojas\/2025\/10\/allexofedrin-120mg-10-comprimidos-revestidos-39028732806\/","title":{"rendered":"Allexofedrin 120mg 10 Comprimidos Revestidos &#8211; 39028732806"},"content":{"rendered":"<h2><\/h2>\n<h3>O pre\u00e7o de Allexofedrin 120mg 10 Comprimidos Revestidos no dia acima especificado era de <strong>R$ 25.39<\/strong>.<\/h3>\n<p>Confira o pre\u00e7o atual aqui: <a href=\"https:\/\/www.awin1.com\/pclick.php?p=39028732806&#038;a=690303&#038;m=68224\" target=\"_blank\" rel=\"noopener sponsored\"><img decoding=\"async\" src=\"https:\/\/ui.awin.com\/images\/upload\/merchant\/profile\/68224.png\" alt=\"Allexofedrin 120mg 10 Comprimidos Revestidos\" \/> &#8211; nas lojas  Drogal _<\/a><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/drogal.vteximg.com.br\/arquivos\/ids\/209272_2\" alt=\"Allexofedrin 120mg 10 Comprimidos Revestidos\" \/><br \/>\nO que \u00e9 o Allexofedrin 120mg e para que serve? Allexofedrin \u00e9 um Anti-histam\u00ednico, cujo o seu princ\u00edpio ativo \u00e9 cloridrato de fexofenadina, que age r\u00e1pido no al\u00edvio desses sintomas. Allexofedrin \u00e9 um rem\u00e9dio antial\u00e9rgico indicado para o tratamento dos sintomas de rea\u00e7\u00f5es al\u00e9rgicas, como espirros, coriza, nariz entupido, conjuntivite al\u00e9rgica e coceira na pele ou nos olhos, nariz e garganta. Allexofedrin n\u00e3o serve para tosses, gripes ou resfriados, e outras doen\u00e7as ou condi\u00e7\u00f5es respirat\u00f3rias que n\u00e3o sejam causadas por rea\u00e7\u00f5es al\u00e9rgicas.    Como tomar Allexofedrin 120mg? Tomar o comprimido do antial\u00e9rgico Allexofedrin com \u00e1gua, por via oral. Este medicamento n\u00e3o deve ser partido ou mastigado.Posologia: Pode variar conforme o uso e a dosagem do medicamento.Rinite al\u00e9rgica: 01 comprimido de 60 mg, 2 vezes ao dia (a cada 12 horas); 01 comprimido de 120 mg 1 vez ao dia; ou 01 comprimido de 180 mg 1 vez ao dia.Urtic\u00e1ria: 01 comprimido de 180 mg 1 vez ao dia.     Como o Allexofedrin 120mg funciona? Allexofedrin \u00e9 um produto com a\u00e7\u00e3o anti-histam\u00ednica utilizado no tratamento sintom\u00e1tico de manifesta\u00e7\u00f5es al\u00e9rgicas. Tempo m\u00e9dio de a\u00e7\u00e3o: Demonstrou-se que Allexofedrin apresenta efeito anti-histam\u00ednico, iniciando-se dentro de 1 hora e alcan\u00e7ando seu efeito m\u00e1ximo dentro de 2 a 3 horas, prolongando-se por 12 horas no m\u00ednimo, ap\u00f3s dose \u00fanica e doses de 2 vezes ao dia, via oral.      Quem n\u00e3o deve usar Allexofedrin? Allexofedrin&nbsp;n\u00e3o deve ser utilizado em pacientes com alergia \u00e0 qualquer componente da f\u00f3rmula. Este medicamento \u00e9 contraindicado para menores de 12 anos.     Quais s\u00e3o as rea\u00e7\u00f5es adversas de Allexofedrin 120mg? Rea\u00e7\u00e3o muito comum: Os eventos adversos mais frequentes relatados em adultos incluem: dor de cabe\u00e7a, sonol\u00eancia, vertigem e n\u00e1useas.<\/p>\n<h4>Aproveite e pesquise o pre\u00e7o deste produto em dezenas de lojas dos marketplaces abaixo:<\/h4>\n<p><a href=\"https:\/\/www.magazinevoce.com.br\/magazineezu\/busca\/Allexofedrin 120mg 10 Comprimidos Revestidos\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png\" alt=\"Pesquise no Magazine eZu\" \/> &#8211; da Parceria MAGALU<\/a>.<\/p>\n<hr \/>\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-5987304558705355\" crossorigin=\"anonymous\"><\/script><br \/>\n<ins class=\"adsbygoogle\" style=\"display: block;\" data-ad-format=\"autorelaxed\" data-ad-client=\"ca-pub-5987304558705355\" data-ad-slot=\"6675008826\"><\/ins><br \/>\n<script>\n     (adsbygoogle = window.adsbygoogle || ).push();\n<\/script><\/p>\n<hr \/>\n<p>Ainda n\u00e3o encontrou a melhor op\u00e7\u00e3o de compra? Oferecemos outra possibilidade de <strong>busca<\/strong>, mais ampla, para <a href=\"https:\/\/ecompare.com.br\/lojas\/resultados-da-pesquisa\/?q=Allexofedrin 120mg 10 Comprimidos Revestidos#gsc.tab=0&amp;gsc.q=Allexofedrin 120mg 10 Comprimidos Revestidos&amp;gsc.page=1\" target=\"_top\" rel=\"noopener\">Allexofedrin 120mg 10 Comprimidos Revestidos, clique e continue <strong>pesquisando&#8230;<\/strong><\/a><\/p>\n<hr \/>\n<p>C\u00f3digo: 3902873280612669R$ 25.3925.3968224R$ 97314<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R$ 25.39 nas lojas <a href=\"https:\/\/www.drogal.com.br\/allexofedrin-120mg-10-comprimidos-revestidos\/p?idsku=12669&#038;utm_source=awin&#038;utm_medium=affiliate&#038;utm_id=&#038;utm_term=690303\" target=\"_blank\" rel=\"sponsored\">Drogal BR<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[5],"tags":[113411],"class_list":["post-2010008","post","type-post","status-publish","format-standard","hentry","category-produtos","tag-drogal-br"],"_links":{"self":[{"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/posts\/2010008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/comments?post=2010008"}],"version-history":[{"count":0,"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/posts\/2010008\/revisions"}],"wp:attachment":[{"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/media?parent=2010008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/categories?post=2010008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecompare.com.br\/lojas\/wp-json\/wp\/v2\/tags?post=2010008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}